


{"id":24818,"date":"2025-02-17T00:00:21","date_gmt":"2025-02-16T23:00:21","guid":{"rendered":"https:\/\/magictowns.al\/?p=24818"},"modified":"2025-06-30T13:26:42","modified_gmt":"2025-06-30T11:26:42","slug":"barbara-oberhauser-albanien-tierschutz","status":"publish","type":"post","link":"https:\/\/magictowns.al\/de\/barbara-oberhauser-albania-animal-welfare\/","title":{"rendered":"Barbara Oberhauser: Life in Albania &#038; Animal Welfare Mission"},"content":{"rendered":"<p><a href=\"https:\/\/www.facebook.com\/profile.php?id=100011861440350\" target=\"_blank\" rel=\"noopener\">Barbara Oberhauser<\/a> war w\u00e4hrend einer Reise im Jahr 2011 von der fr\u00f6hlichen und gastfreundlichen Gemeinschaft Albaniens fasziniert. Sie machte sich die Kultur des Landes zu eigen und widmete sich der Aufgabe, etwas Positives zu bewirken, insbesondere im Tierschutz. Ihre Reise bietet eine frische, leidenschaftliche Perspektive auf das Leben in Albanien.<\/p>\n<p>Barbara ist 60 Jahre alt und kommt urspr\u00fcnglich aus Kitzb\u00fchel in Tirol in \u00d6sterreich. Motiviert durch ihre Liebe zu ihrem neuen Land, engagierte sich Barbara aktiv in den \u00f6rtlichen Gemeinden und setzte sich f\u00fcr eine bessere Behandlung von Tieren ein. Ihre Arbeit hat das Bewusstsein f\u00fcr den Tierschutz gesch\u00e4rft und dazu beigetragen, die Beziehungen zwischen Einheimischen und Auswanderern zu st\u00e4rken.<\/p>\n<p>Folgen Sie uns auf Barbaras Reise durch Albanien.<\/p>\n<figure id=\"attachment_24824\" aria-describedby=\"caption-attachment-24824\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img decoding=async data-opt-id=1572444581  fetchpriority=\"high\" class=\"wp-image-24824 size-full\" src=\"https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:auto\/h:auto\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg\" alt=\"Barbara Oberhauser\" width=\"960\" height=\"960\" title=\"\" srcset=\"https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:960\/h:960\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 960w, https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:300\/h:300\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 300w, https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:150\/h:150\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 150w, https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:768\/h:768\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 768w, https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:12\/h:12\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 12w, https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:256\/h:256\/q:mauto\/g:sm\/f:best\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 256w, https:\/\/ml4ds5noqxtv.i.optimole.com\/cb:nu7s.344e2\/w:960\/h:960\/q:mauto\/g:sm\/f:best\/dpr:2\/https:\/\/magictowns.al\/wp-content\/uploads\/2025\/01\/Barbara-Oberhauser.jpg 2x\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-24824\" class=\"wp-caption-text\">Barbara Oberhauser Tierschutzarbeit machen.<\/figcaption><\/figure>\n<h2><b>AN Encounter with Albania<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Im Jahr 2011 ver\u00e4nderte ein ungeplanter Umweg \u00fcber Albanien ihr Leben.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Ich war auf der R\u00fcckfahrt von Griechenland nach \u00d6sterreich und beschloss, durch Albanien zu fahren. Von dem Moment an, als ich einreiste, war ich von der Freundlichkeit der Menschen und der Sch\u00f6nheit des Landes \u00fcberw\u00e4ltigt. Alles, was ich \u00fcber Albanien geh\u00f6rt hatte, war so negativ, aber ich fand das genaue Gegenteil. Es ist ein wundervoller Ort, und das Zusammenleben der verschiedenen Religionen hier ist wirklich inspirierend.\"<\/span><\/p><\/blockquote>\n<h2><b>Eine Familienverbindung in Karpen<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Im Laufe der Jahre vertiefte sich ihre Verbundenheit mit Albanien, insbesondere durch ihre Beziehung zur Familie Peposhi, die den Campingplatz Pa Emer in Karpen, s\u00fcdlich von Durr\u00ebs, betreibt.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Sie sind mir hier ans Herz gewachsen. Ihre Freundlichkeit und Gastfreundschaft spiegeln das Beste von Albanien wider. Der Aufenthalt bei ihnen hat mir das Gef\u00fchl gegeben, Teil der Familie zu sein.\"<\/span><\/p><\/blockquote>\n<h2><b>Lebenshaltungskosten: Damals und heute<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Als sie zum ersten Mal nach Albanien kam, waren die Lebenshaltungskosten bemerkenswert niedrig.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Fr\u00fcher war es f\u00fcr Europ\u00e4er sehr billig. Jetzt sind die Preise gestiegen, vor allem im S\u00fcden, der immer touristischer und kommerzieller geworden ist. Der Norden hingegen ist authentisch geblieben. Insgesamt ist es f\u00fcr uns immer noch erschwinglich, aber die Ver\u00e4nderungen sind sp\u00fcrbar.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Obwohl die Preise gestiegen sind, <a href=\"https:\/\/magictowns.al\/de\/ist-albanien-fur-auswanderer-erschwinglich\/\">Ausl\u00e4nder in Albanien finden es immer noch relativ erschwinglich<\/a> und k\u00f6nnen ein komfortables und friedliches Leben genie\u00dfen.<\/span><\/p>\n<h2><b>FALLING IN LOVE WITH Traditions\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Die Anpassung an das albanische Leben war ein nat\u00fcrlicher Prozess. Sie bewundert die vielf\u00e4ltige Landschaft Albaniens und seine akzeptierende Gemeinschaft,\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Ich habe immer gesch\u00e4tzt, dass <a href=\"https:\/\/magictowns.al\/de\/albanische-neujahrstraditionen\/\">Traditionen<\/a>und Albanien hat so viele sch\u00f6ne Orte. Was ich am meisten liebe, ist, wie offen und friedlich die verschiedenen Religionen hier nebeneinander existieren. Das ist etwas, was man nicht an vielen Orten sieht. F\u00fcr mich ist das ein Teil dessen, was das Leben hier so besonders macht.\"<\/span><\/p><\/blockquote>\n<h2><b>Sensibilisierung f\u00fcr streunende Tiere<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Ihre Leidenschaft f\u00fcr Albanien gilt auch den Tieren, insbesondere den unz\u00e4hligen Streunern.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Es gibt hier keine staatliche Unterst\u00fctzung f\u00fcr den Tierschutz. Es ist herzzerrei\u00dfend.\"\u00a0<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Die Zusammenarbeit mit Organisationen wie <a href=\"https:\/\/www.jetatierundmensch.ch\/\" target=\"_blank\" rel=\"noopener\">JETA Tier und Mensch<\/a>macht sie auf die harte Realit\u00e4t von streunenden Hunden und Katzen aufmerksam.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Hunde werden meist als Schutztiere betrachtet, angekettet oder in K\u00e4figen gehalten, und Katzen werden noch weniger gesch\u00e4tzt. Die einzige Unterst\u00fctzung kommt von privaten Gruppen und Spenden\".<\/span><\/p><\/blockquote>\n<h2><b>Gemeinschaft aufbauen und Ma\u00dfnahmen ergreifen<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Trotz dieser Herausforderungen bleibt sie hoffnungsvoll und aktiv.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Soziale Medien sind ein gro\u00dfartiges Instrument, um mit anderen in Kontakt zu treten, die sich f\u00fcr Tiere einsetzen. Auch Auswanderer und Touristen k\u00f6nnen helfen, indem sie Futterstellen einrichten, spenden oder ihre Erfahrungen online teilen. Selbst kleine Aktionen k\u00f6nnen einen gro\u00dfen Unterschied machen.<\/span><\/p><\/blockquote>\n<h2><b>Kulturelle Unterschiede und respektvolle Anpassung<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Auf die Frage nach der Anpassung an die albanische Kultur antwortet sie, dass es wichtig sei, zu verstehen.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Die Dinge funktionieren nicht so wie in Europa, und das ist in Ordnung. Man muss Albanien als das akzeptieren, was es ist: ein freies Land mit eigenen Regeln und einer eigenen Lebensart. Der Schl\u00fcssel ist, die Menschen nicht zu belehren, sondern ihre Kultur anzunehmen.<\/span><\/p><\/blockquote>\n<h2><b>Ratschl\u00e4ge f\u00fcr Neuank\u00f6mmlinge<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">F\u00fcr alle, die einen Umzug nach Albanien in Erw\u00e4gung ziehen, ist ihr Rat klar.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Betrachten Sie nicht nur die Sonnenseite des Lebens hier. Lernen Sie die allt\u00e4gliche Realit\u00e4t, die Herausforderungen und Unterschiede kennen. Seien Sie offen f\u00fcr neue Erfahrungen, respektieren Sie die Traditionen und verstehen Sie, dass das Leben hier vielleicht nicht so reibungslos abl\u00e4uft wie in Europa. Aber wenn Sie aufgeschlossen sind, werden Sie sich in diesen Ort verlieben.<\/span><\/p><\/blockquote>\n<h2><b>Auf dem Weg zum Wandel<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Trotz der Probleme, mit denen Albanien insbesondere im Bereich des Tierschutzes konfrontiert ist, glaubt sie, dass ein Wandel m\u00f6glich ist.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\"Die j\u00fcngere Generation gibt mir Hoffnung. Mit dem Aufkommen der sozialen Medien und dem verst\u00e4rkten Kontakt zur Au\u00dfenwelt w\u00e4chst das Bewusstsein. Meine Hoffnung ist, dass Albanien eines Tages Systeme zum Schutz seiner Tiere und zur Erhaltung seiner einzigartigen Lebensweise entwickelt.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Ihre Geschichte ist eine Geschichte der Liebe, des Handelns und der Hoffnung, ein Zeugnis f\u00fcr die Sch\u00f6nheit Albaniens und den Unterschied, den ein einzelner Mensch an einem Ort, den er sein Zuhause nennt, bewirken kann.<\/span><\/p>\n\r\n\t\t\t<div id=\"daexthefu-container\"\r\n\t\t\t\tclass=\"daexthefu-container daexthefu-layout-side-by-side daexthefu-alignment-center\"\r\n\t\t\t\tdata-post-id=\"24818\">\r\n\r\n\t\t\t\t<div class=\"daexthefu-feedback\">\r\n\t\t\t\t\t<div class=\"daexthefu-text\">\r\n\t\t\t\t\t\t<h3 class=\"daexthefu-title\">War dies hilfreich?<\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"daexthefu-buttons-container\">\r\n\t\t\t\t\t\t<div class=\"daexthefu-buttons\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-yes daexthefu-button daexthefu-button-type-text\" data-value=\"1\">\r\n\t\t\t\t<div class=\"daexthefu-button-text\">\u2705 Ja<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-no daexthefu-button daexthefu-button-type-text\" data-value=\"0\">\r\n\t\t\t\t<div class=\"daexthefu-button-text\">\u274c Nein<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-comment\">\r\n\t\t\t\t\t<div class=\"daexthefu-comment-top-container\">\r\n\t\t\t\t\t\t<label id=\"daexthefu-comment-label\" class=\"daexthefu-comment-label\"><\/label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-container\">\r\n\t\t\t\t\t\t\t\t<div id=\"daexthefu-comment-character-counter-number\"\r\n\t\t\t\t\t\t\t\t\tclass=\"daexthefu-comment-character-counter-number\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-text\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<textarea id=\"daexthefu-comment-textarea\" class=\"daexthefu-comment-textarea\"\r\n\t\t\t\t\t\t\t\tplaceholder=\"Geben Sie Ihre Nachricht ein\"\r\n\t\t\t\t\t\t\t\tmaxlength=\"\t\t\t\t\t\t\t\t400\t\t\t\t\t\t\t\t\t\"><\/textarea>\r\n\t\t\t\t\t<div class=\"daexthefu-comment-buttons-container\">\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-submit daexthefu-button\">Einreichen<\/button>\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-cancel daexthefu-button\">Abbrechen<\/button>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-successful-submission-text\">Vielen Dank f\u00fcr Ihr Feedback!<\/div>\r\n\r\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Entdecken Sie Barbaras Reise durch Albanien und erfahren Sie mehr \u00fcber die Sch\u00f6nheit des Landes, seine Kultur und ihre Bem\u00fchungen um den Tierschutz und den Aufbau von Gemeinschaften.<\/p>","protected":false},"author":20,"featured_media":24821,"comment_status":"closed","ping_status":"open","sticky":false,"template":"single-fullwidth.php","format":"standard","meta":{"_acf_changed":false,"_helpful_status":1,"footnotes":"","_members_access_role":[],"_members_access_error":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":null,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_bluesky_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[562],"tags":[558],"class_list":["post-24818","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interviews","tag-albania"],"acf":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/posts\/24818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/comments?post=24818"}],"version-history":[{"count":8,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/posts\/24818\/revisions"}],"predecessor-version":[{"id":26169,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/posts\/24818\/revisions\/26169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/media\/24821"}],"wp:attachment":[{"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/media?parent=24818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/categories?post=24818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magictowns.al\/de\/wp-json\/wp\/v2\/tags?post=24818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}